{"id":2545,"date":"2026-07-12T22:54:11","date_gmt":"2026-07-13T03:54:11","guid":{"rendered":"https:\/\/scholagregorianabogota.com\/?page_id=2545"},"modified":"2026-07-13T14:25:41","modified_gmt":"2026-07-13T19:25:41","slug":"historia","status":"publish","type":"page","link":"https:\/\/scholagregorianabogota.com\/index.php\/historia\/","title":{"rendered":"24 a\u00f1os de historia&#8230;"},"content":{"rendered":"\n<div class=\"wp-block-group wp-container-content-e29552f7 is-layout-flow wp-container-core-group-is-layout-b76e4779 wp-block-group-is-layout-flow\">\n<p class=\"has-text-align-center has-text-color has-link-color wp-elements-1 wp-block-paragraph\" style=\"color:#191970;font-size:clamp(0.875rem, 0.875rem + ((1vw - 0.2rem) * 1.063), 1.3rem);\"><a href=\"https:\/\/photos.app.goo.gl\/hi58rcBNrNZukXyM8\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Clic aqu\u00ed para ver \u00e1lbum de fotos<\/a><\/p>\n\n\n<div class=\"gb-container gb-container-3cb4e62b\">\n<div class=\"gb-container gb-container-5ea096fe\">\n\n<figure class=\"gb-block-image gb-block-image-b3cf010f\"><img loading=\"lazy\" decoding=\"async\" width=\"272\" height=\"382\" class=\"gb-image gb-image-b3cf010f\" src=\"https:\/\/scholagregorianabogota.com\/wp-content\/uploads\/2024\/01\/Captura-de-pantalla-2024-01-30-a-las-11.25.13-a.-m.png\" alt=\"Padre Emmanuel L\u00f6we\" title=\"Captura-de-pantalla-2024-01-30-a-las-11.25.13-a.-m\" srcset=\"https:\/\/scholagregorianabogota.com\/wp-content\/uploads\/2024\/01\/Captura-de-pantalla-2024-01-30-a-las-11.25.13-a.-m.png 272w, https:\/\/scholagregorianabogota.com\/wp-content\/uploads\/2024\/01\/Captura-de-pantalla-2024-01-30-a-las-11.25.13-a.-m-214x300.png 214w\" sizes=\"auto, (max-width: 272px) 100vw, 272px\" \/>\n<figcaption class=\"gb-headline gb-headline-830207c6 gb-headline-text\">Padre Emmanuel Stephan L\u00f6we O.S.B.<\/figcaption>\n<\/figure>\n\n<\/div>\n\n<div class=\"gb-container gb-container-8a78c7fc\">\n\n<p class=\"gb-headline gb-headline-de5f6614 gb-headline-text\">La Schola Gregoriana de Bogot\u00e1 fue fundada en el a\u00f1o <strong>2002<\/strong> por el padre benedictino <strong>Emmanuel Stephan L\u00f6we,<\/strong> organista y especialista en Canto Gregoriano, y por el padre carmelita <strong>Francisco Alejandro Tob\u00f3n Gonz\u00e1les<\/strong>, entonces alumno de L\u00f6we.<br><br>A finales de <strong>2004<\/strong>, la conducci\u00f3n qued\u00f3 en manos del padre Tob\u00f3n.<\/p>\n\n<\/div>\n<\/div>\n\n<div class=\"gb-container gb-container-74c33a04\">\n<div class=\"gb-container gb-container-2ecda2c2\">\n\n<figure class=\"gb-block-image gb-block-image-d37b3dd7\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"2048\" class=\"gb-image gb-image-d37b3dd7\" src=\"https:\/\/scholagregorianabogota.com\/wp-content\/uploads\/2024\/11\/Padre-Alejandro-Tobon.jpg\" alt=\"Padre Alejandro Tob\u00f3n O.C.D.\" title=\"Padre Alejandro Tob\u00f3n\" srcset=\"https:\/\/scholagregorianabogota.com\/wp-content\/uploads\/2024\/11\/Padre-Alejandro-Tobon.jpg 2048w, https:\/\/scholagregorianabogota.com\/wp-content\/uploads\/2024\/11\/Padre-Alejandro-Tobon-300x300.jpg 300w, https:\/\/scholagregorianabogota.com\/wp-content\/uploads\/2024\/11\/Padre-Alejandro-Tobon-1024x1024.jpg 1024w, https:\/\/scholagregorianabogota.com\/wp-content\/uploads\/2024\/11\/Padre-Alejandro-Tobon-150x150.jpg 150w, https:\/\/scholagregorianabogota.com\/wp-content\/uploads\/2024\/11\/Padre-Alejandro-Tobon-768x768.jpg 768w, https:\/\/scholagregorianabogota.com\/wp-content\/uploads\/2024\/11\/Padre-Alejandro-Tobon-1536x1536.jpg 1536w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/>\n<figcaption class=\"gb-headline gb-headline-748fd12e gb-headline-text\">Padre Francisco Alejandro Tob\u00f3n Gonz\u00e1les O.C.D.<\/figcaption>\n<\/figure>\n\n<\/div>\n\n<div class=\"gb-container gb-container-5bc531b4\">\n\n<p class=\"gb-headline gb-headline-c727958a gb-headline-text\">A comienzos de <strong>2014<\/strong>, la direcci\u00f3n qued\u00f3 en manos del hermano carmelita <strong>Fray Pablo Andr\u00e9s Rodr\u00edguez<\/strong> (hoy sacerdote). Bajo su orientaci\u00f3n, la SGB prepar\u00f3 un repertorio de m\u00fasica en el Carmelo Descalzo y realiz\u00f3 una grabaci\u00f3n en la catedral de Bogot\u00e1 y en la capilla de las Facultades Eclesi\u00e1sticas de la Universidad Javeriana. El director asistente fue el maestro <strong>Sebasti\u00e1n Vega Qui\u00f1ones<\/strong>, impulsor incansable del trabajo de la agrupaci\u00f3n, quien posteriormente asume la direcci\u00f3n principal hasta el presente.<\/p>\n\n<\/div>\n<\/div>\n\n<div class=\"gb-container gb-container-8583f4b9\">\n<div class=\"gb-container gb-container-6f897e02\">\n\n<figure class=\"gb-block-image gb-block-image-37f45d91\"><img loading=\"lazy\" decoding=\"async\" width=\"381\" height=\"794\" class=\"gb-image gb-image-37f45d91\" src=\"https:\/\/scholagregorianabogota.com\/wp-content\/uploads\/2024\/01\/img-0451-1.png\" alt=\"\" title=\"img-0451-1\" srcset=\"https:\/\/scholagregorianabogota.com\/wp-content\/uploads\/2024\/01\/img-0451-1.png 381w, https:\/\/scholagregorianabogota.com\/wp-content\/uploads\/2024\/01\/img-0451-1-144x300.png 144w\" sizes=\"auto, (max-width: 381px) 100vw, 381px\" \/>\n<figcaption class=\"gb-headline gb-headline-3e5cc8f0 gb-headline-text\">Sebasti\u00e1n Vega Qui\u00f1ones, actual director de la SGB, a su izquierda, Padre Pablo Andr\u00e9s Rodr\u00edguez O.C.D.<\/figcaption>\n<\/figure>\n\n<\/div>\n\n<div class=\"gb-container gb-container-08c209c6\">\n<div class=\"gb-container gb-container-7b264a5d\">\n\n<p class=\"gb-headline gb-headline-4fc726d3 gb-headline-text\">La <strong>SGB<\/strong> ha participado en importantes solemnidades lit\u00fargicas en la catedral primada de Bogot\u00e1, tanto&nbsp;<em>a cappella<\/em>&nbsp;como con organistas de la talla de Pascal Marsault, Wolfgang Seifen, Mauricio Nasi y Juan David Barrera. Adem\u00e1s, ha realizado innumerables conciertos y liturgias en varias ciudades de Colombia. Tambi\u00e9n particip\u00f3 en la edici\u00f3n del a\u00f1o <strong>2018 <\/strong>del <a href=\"https:\/\/www.festivalwatou.be\/en\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">International Gregorian Festival<\/a>, en Watou (B\u00e9lgica) como \u00fanica agrupaci\u00f3n latinoamericana.<\/p>\n\n\n\n<div style=\"height:17px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-b93ccffa wp-block-buttons-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--10);margin-bottom:var(--wp--preset--spacing--10)\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100 is-style-fill\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/maps.app.goo.gl\/vVqh5uLmk6BQh5Ha6\" style=\"text-decoration:underline\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Ver<strong> lugares donde la Schola<\/strong> <strong>se ha presentado en concierto<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<details class=\"wp-block-details has-text-color has-link-color has-heading-font-family wp-elements-2 is-layout-flow wp-block-details-is-layout-flow\" style=\"color:#ff0000;font-size:clamp(0.929rem, 0.929rem + ((1vw - 0.2rem) * 1.178), 1.4rem);\"><summary>Ver lista de ex-integrantes:<\/summary>\n<ul style=\"margin-right:0;margin-left:0;padding-top:0.5rem;padding-right:var(--wp--preset--spacing--30);padding-bottom:0;padding-left:var(--wp--preset--spacing--30)\" class=\"wp-block-list is-style-default has-small-font-size\">\n<li>Padre Emmanuel Stephan L\u00f6we O.S.B. (Director de 2002 a 2004)<\/li>\n\n\n\n<li>Padre Francisco Alejandro Tob\u00f3n Gonz\u00e1les O.C.D. (Director de 2004 a 2014)<\/li>\n\n\n\n<li>Alicia Santos<\/li>\n\n\n\n<li>Ang\u00e9lica Daza Enciso<\/li>\n\n\n\n<li>Juan Fernando&nbsp;Hoyos<\/li>\n\n\n\n<li>Padre Pablo Andr\u00e9s Rodr\u00edguez O.C.D. (Director de 2014 a 2016)<\/li>\n\n\n\n<li>Carmen Yepes<\/li>\n\n\n\n<li>Claudia \u00c1vila<\/li>\n\n\n\n<li>Diana Farley Rodr\u00edguez Mu\u00f1oz<\/li>\n\n\n\n<li>Juliana Velasco Guerrero<\/li>\n\n\n\n<li>Germ\u00e1n Eduardo P\u00e1ez Chaustre<\/li>\n\n\n\n<li>Jhonathan \u00c1vila<\/li>\n\n\n\n<li>David Madrid<\/li>\n\n\n\n<li>Padre Jorge Enrique Salcedo<\/li>\n\n\n\n<li>Carlos Julio Herrera<\/li>\n\n\n\n<li>Rafael Lykos Rivas<\/li>\n\n\n\n<li>Juan Ricardo Novoa<\/li>\n\n\n\n<li>Jes\u00fas David Gil<\/li>\n\n\n\n<li>Juan David Tatis Gonz\u00e1les<\/li>\n\n\n\n<li>Carlos Eduardo Nieto<\/li>\n\n\n\n<li>Sebasti\u00e1n Araujo Acosta<\/li>\n\n\n\n<li>Jos\u00e9 Manuel Fl\u00f3rez Alviar<\/li>\n<\/ul>\n<\/details>\n\n<\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Clic aqu\u00ed para ver \u00e1lbum de fotos La Schola Gregoriana de Bogot\u00e1 fue fundada en el a\u00f1o 2002 por el padre benedictino Emmanuel Stephan L\u00f6we, organista y especialista en Canto Gregoriano, y por el padre carmelita Francisco Alejandro Tob\u00f3n Gonz\u00e1les, entonces alumno de L\u00f6we. A finales de 2004, la conducci\u00f3n qued\u00f3 en manos del padre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"bBlocksCursorData":"","footnotes":""},"class_list":["post-2545","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/scholagregorianabogota.com\/index.php\/wp-json\/wp\/v2\/pages\/2545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scholagregorianabogota.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/scholagregorianabogota.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/scholagregorianabogota.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/scholagregorianabogota.com\/index.php\/wp-json\/wp\/v2\/comments?post=2545"}],"version-history":[{"count":5,"href":"https:\/\/scholagregorianabogota.com\/index.php\/wp-json\/wp\/v2\/pages\/2545\/revisions"}],"predecessor-version":[{"id":2569,"href":"https:\/\/scholagregorianabogota.com\/index.php\/wp-json\/wp\/v2\/pages\/2545\/revisions\/2569"}],"wp:attachment":[{"href":"https:\/\/scholagregorianabogota.com\/index.php\/wp-json\/wp\/v2\/media?parent=2545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}